{"id":6439,"count":8,"description":"","link":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/","name":"Barcelona","slug":"barcelona","taxonomy":"category","parent":4183,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Barcelona Archives - Chic . Explore . ThinkerTen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Barcelona Archives - Chic . Explore . ThinkerTen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Chic . Explore . ThinkerTen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/spain\\\/barcelona\\\/\",\"url\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/spain\\\/barcelona\\\/\",\"name\":\"Barcelona Archives - Chic . Explore . ThinkerTen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/spain\\\/barcelona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/spain\\\/barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Europe\",\"item\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Spain\",\"item\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/category\\\/europe\\\/spain\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/\",\"name\":\"Chic . Explore . ThinkerTen\",\"description\":\"My Style ~ My Journey ~ My Inspiration\",\"publisher\":{\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#organization\",\"name\":\"ThinkerTen\",\"url\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Logo.jpg\",\"width\":344,\"height\":88,\"caption\":\"ThinkerTen\"},\"image\":{\"@id\":\"https:\\\/\\\/thinkerten.com\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kumamonjengpage\",\"https:\\\/\\\/www.instagram.com\\\/kumamonjeng\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCuY8XGUKQM_uc9SRgr7FCVQ\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Barcelona Archives - Chic . Explore . ThinkerTen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/","og_locale":"en_US","og_type":"article","og_title":"Barcelona Archives - Chic . Explore . ThinkerTen","og_url":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/","og_site_name":"Chic . Explore . ThinkerTen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/","url":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/","name":"Barcelona Archives - Chic . Explore . ThinkerTen","isPartOf":{"@id":"https:\/\/thinkerten.com\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thinkerten.com\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Europe","item":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/"},{"@type":"ListItem","position":3,"name":"Spain","item":"https:\/\/thinkerten.com\/wordpress\/category\/europe\/spain\/"},{"@type":"ListItem","position":4,"name":"Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/thinkerten.com\/wordpress\/#website","url":"https:\/\/thinkerten.com\/wordpress\/","name":"Chic . Explore . ThinkerTen","description":"My Style ~ My Journey ~ My Inspiration","publisher":{"@id":"https:\/\/thinkerten.com\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thinkerten.com\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/thinkerten.com\/wordpress\/#organization","name":"ThinkerTen","url":"https:\/\/thinkerten.com\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thinkerten.com\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/thinkerten.com\/wordpress\/wp-content\/uploads\/2021\/02\/Logo.jpg","contentUrl":"https:\/\/thinkerten.com\/wordpress\/wp-content\/uploads\/2021\/02\/Logo.jpg","width":344,"height":88,"caption":"ThinkerTen"},"image":{"@id":"https:\/\/thinkerten.com\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kumamonjengpage","https:\/\/www.instagram.com\/kumamonjeng\/","https:\/\/www.youtube.com\/channel\/UCuY8XGUKQM_uc9SRgr7FCVQ\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/thinkerten.com\/wordpress\/wp-json\/wp\/v2\/categories\/6439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thinkerten.com\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/thinkerten.com\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/thinkerten.com\/wordpress\/wp-json\/wp\/v2\/categories\/4183"}],"wp:post_type":[{"href":"https:\/\/thinkerten.com\/wordpress\/wp-json\/wp\/v2\/posts?categories=6439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}